{"id":39148,"date":"2023-04-25T13:25:13","date_gmt":"2023-04-25T13:25:13","guid":{"rendered":"https:\/\/iberopress.es\/index.php\/2023\/04\/25\/uno-de-los-primeros-metaversos-de-salud-lucatia\/"},"modified":"2023-04-25T13:25:13","modified_gmt":"2023-04-25T13:25:13","slug":"uno-de-los-primeros-metaversos-de-salud-lucatia","status":"publish","type":"post","link":"https:\/\/iberopress.es\/index.php\/2023\/04\/25\/uno-de-los-primeros-metaversos-de-salud-lucatia\/","title":{"rendered":"Uno de los primeros metaversos de salud, Lucatia"},"content":{"rendered":"<p>Uno de los primeros metaversos de salud, Lucatia<\/p>\n<p>Uno de los primeros metaversos de salud, Lucatia<\/p>\n<div>\n<p>Seg\u00fan indica la Organizaci\u00f3n Mundial de la Salud (OMS), \u201clos avances en el \u00e1rea de <em>big data<\/em> e inteligencia artificial han abierto nuevas oportunidades para monitorear la salud\u201d. Otro desarrollo tecnol\u00f3gico que funciona en este mismo sentido es el <a href=\"https:\/\/www.lucatia.com\/\" rel=\"noreferrer\">metaverso<\/a>. En estas interfaces o espacios virtuales, es posible interactuar con profesionales de la salud e intercambiar informaci\u00f3n.<\/p>\n<p>En particular, el metaverso de bienestar y salud creado por la empresa <a href=\"https:\/\/www.lucatia.com\/\" rel=\"noreferrer\">Lucatia<\/a> es dirigido por profesionales de distintos hospitales de Catalu\u00f1a. En este espacio, pacientes, familiares, profesionales y visitantes pueden asistir en directo a eventos de formaci\u00f3n, divulgaci\u00f3n m\u00e9dica y a otros actos l\u00fadicos y sociales.<\/p>\n<h2 id=\"el-distrito-de-salud-virtual-lucatia-metaverse\">El distrito de salud virtual Lucatia Metaverse<\/h2>\n<p>Este espacio interactivo y digital est\u00e1 compuesto por varias edificaciones llamadas Lucatia Towers. Son modernos edificios corporativos que albergan a diferentes empresas del sector de la salud como, por ejemplo, cl\u00ednicas o laboratorios. Los interiores de cada una de estas instalaciones est\u00e1n personalizados y todos cuentan con salas virtuales para realizar reuniones.<\/p>\n<p>Adem\u00e1s, en este metaverso, <strong>es posible intercambiar informaci\u00f3n con un mostrador de atenci\u00f3n al paciente y resolver dudas sobre el funcionamiento de distintos servicios sanitarios<\/strong>. En estos casos, los usuarios simulan la llegada al <em>hall <\/em>de un edificio, como si se tratara de un videojuego. Al estar dentro de alguno de estos edificios virtuales, es posible interaccionar con varios elementos o puntos de informaci\u00f3n flotantes que est\u00e1n distribuidos por estos espacios.<\/p>\n<h2 id=\"mith-el-hospital-virtual-del-metaverso-de-lucatia\">MITH: el hospital virtual del metaverso de Lucatia<\/h2>\n<p>MITH (Medical Internet of Things Hospital) es el nombre del hospital central que est\u00e1 dentro del metaverso creado por Lucatia. <strong>Uno de los objetivos de este centro es la incorporaci\u00f3n de interacciones en tiempo real con paciente mediante sistemas de videoconferencias apoyados en tecnolog\u00eda 5G<\/strong>. De esta manera, ser\u00eda posible desarrollar consultar virtuales en tiempo real.<\/p>\n<p>Adem\u00e1s, MITH busca proporcionar a m\u00e9dicos, psic\u00f3logos, fisioterapeutas y distintos profesionales de la salud un espacio virtual y aplicaciones que permitan sostener interacciones con pacientes sin riesgo para la salud y sin necesidad de efectuar desplazamientos hasta consultas o centros m\u00e9dicos.<\/p>\n<p>Al mismo tiempo, en este hospital virtual, <strong>los profesionales pueden acceder a avanzadas herramientas de formaci\u00f3n m\u00e9dica y sanitaria y a informaci\u00f3n sobre los \u00faltimos avances disponibles para practicar intervenciones m\u00e9dicas<\/strong>. Este es un paso m\u00e1s en el uso de tecnolog\u00eda como realidad virtual y realidad aumentada, que en el mundo cient\u00edfico en general se vienen estudiando desde hace 20 a\u00f1os.<\/p>\n<p>El metaverso de Lucatia ofrece un espacio virtual y seguro para que profesionales sanitarios, pacientes y otros usuarios puedan sostener distintas interacciones que sirvan para mejorar la prevenci\u00f3n y tratamiento de la salud.<\/p>\n<p>The post <a rel=\"nofollow\" href=\"https:\/\/tecnobitt.com\/uno-de-los-primeros-metaversos-de-salud-lucatia\/\">Uno de los primeros metaversos de salud, Lucatia<\/a> appeared first on <a rel=\"nofollow\" href=\"https:\/\/tecnobitt.com\/\">TecnoBitt :- Un bit de tecnolog\u00eda diaria<\/a>.<\/p>\n<\/div>\n<p><img decoding=\"async\" class=\"wpe_imgrss\" src=\"https:\/\/tecnobitt.com\/wp-content\/uploads\/2023\/04\/img_c_64240c75aa5e1.jpg\"><\/p>\n<p><img decoding=\"async\" class=\"wpe_imgrss\" src=\"https:\/\/diarioemprendedor.com\/wp-content\/uploads\/2023\/04\/img_c_64240c75aa5e1.jpg\"><\/p>\n","protected":false},"excerpt":{"rendered":"Uno de los primeros metaversos de salud, Lucatia Uno de los primeros metaversos de salud, Lucatia Seg\u00fan indica&hellip;","protected":false},"author":2,"featured_media":39149,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"csco_display_header_overlay":false,"csco_singular_sidebar":"","csco_page_header_type":"","csco_page_load_nextpost":"","csco_post_video_location":[],"csco_post_video_location_hash":"","csco_post_video_url":"","csco_post_video_bg_start_time":0,"csco_post_video_bg_end_time":0,"footnotes":""},"categories":[554,426,762,729,427,763,764,765,466,766],"tags":[114],"class_list":["post-39148","post","type-post","status-publish","format-standard","has-post-thumbnail","category-actualidad","category-destacado","category-ecocistema","category-entrevistas","category-featured","category-inversiones","category-noticia","category-noticias","category-startups","category-venture-capital","tag-destacado","cs-entry","cs-video-wrap"],"_links":{"self":[{"href":"https:\/\/iberopress.es\/index.php\/wp-json\/wp\/v2\/posts\/39148","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/iberopress.es\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/iberopress.es\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/iberopress.es\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/iberopress.es\/index.php\/wp-json\/wp\/v2\/comments?post=39148"}],"version-history":[{"count":0,"href":"https:\/\/iberopress.es\/index.php\/wp-json\/wp\/v2\/posts\/39148\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/iberopress.es\/index.php\/wp-json\/wp\/v2\/media\/39149"}],"wp:attachment":[{"href":"https:\/\/iberopress.es\/index.php\/wp-json\/wp\/v2\/media?parent=39148"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/iberopress.es\/index.php\/wp-json\/wp\/v2\/categories?post=39148"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/iberopress.es\/index.php\/wp-json\/wp\/v2\/tags?post=39148"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}