{"id":38781,"date":"2023-04-18T10:25:46","date_gmt":"2023-04-18T10:25:46","guid":{"rendered":"https:\/\/iberopress.es\/index.php\/2023\/04\/18\/bim-y-el-mitma-favorecen-un-mejor-uso-de-las-normas-en-la-administracion-publica\/"},"modified":"2023-04-18T10:25:46","modified_gmt":"2023-04-18T10:25:46","slug":"bim-y-el-mitma-favorecen-un-mejor-uso-de-las-normas-en-la-administracion-publica","status":"publish","type":"post","link":"https:\/\/iberopress.es\/index.php\/2023\/04\/18\/bim-y-el-mitma-favorecen-un-mejor-uso-de-las-normas-en-la-administracion-publica\/","title":{"rendered":"BIM y el MITMA favorecen un mejor uso de las normas en la Administraci\u00f3n P\u00fablica"},"content":{"rendered":"<p>BIM y el MITMA favorecen un mejor uso de las normas en la Administraci\u00f3n P\u00fablica<\/p>\n<p>BIM y el MITMA favorecen un mejor uso de las normas en la Administraci\u00f3n P\u00fablica<\/p>\n<div>\n<p>\/COMUNICAE\/ <\/p>\n<p><a href=\"https:\/\/static.comunicae.com\/photos\/notas\/1245041\/normas-bim.jpg\" target=\"_blank\" class=\"fotonota\" rel=\"noopener\"> <img decoding=\"async\" src=\"https:\/\/static.comunicae.com\/photos\/notas\/1245041\/normas-bim.jpg\" border=\"0\" class=\"postImage\" alt=\"\"><\/a><\/p>\n<p>El Ministerio de Transportes, Movilidad y Agenda Urbana ha firmado un convenio de colaboraci\u00f3n con la Asociaci\u00f3n Espa\u00f1ola de Normalizaci\u00f3n, UNE<\/p>\n<p>La metodolog\u00eda BIM sigue extendiendo sus usos y ventajas en la Administraci\u00f3n P\u00fablica. A trav\u00e9s del Ministerio de Transportes, Movilidad y Agenda Urbana (MITMA), Building Information Modeling est\u00e1 presente en un proyecto que busca fomentar un mejor uso de las normas en dicho \u00e1mbito.<\/p>\n<p>Para ello, MITMA ha firmado un convenio de colaboraci\u00f3n con la Asociaci\u00f3n Espa\u00f1ola de Normalizaci\u00f3n, UNE, cuyo objeto es establecer las bases necesarias que redunden en un mejor uso de las normas t\u00e9cnicas en las disposiciones legislativas y como apoyo a las pol\u00edticas p\u00fablicas del Ministerio.<\/p>\n<p>En este sentido, seg\u00fan ha informado recientemente MITMA en un comunicado, \u00ablas acciones est\u00e1n orientadas a profundizar en el modelo de colaboraci\u00f3n actual, como la participaci\u00f3n del Ministerio en comit\u00e9s de normalizaci\u00f3n, \u00f3rganos de gobierno de UNE, participaci\u00f3n de UNE en comisiones y grupos de inter\u00e9s del departamento de Transportes, Movilidad y Agenda Urbana, as\u00ed como la participaci\u00f3n en acciones conjuntas de difusi\u00f3n y en propuestas que buscan velar por la protecci\u00f3n de la propiedad intelectual de las normas de UNE\u00bb. Adem\u00e1s, el acuerdo contempla nuevas formas de colaboraci\u00f3n como la promoci\u00f3n y el desarrollo de convenios espec\u00edficos, la dinamizaci\u00f3n y el intercambio de informaci\u00f3n mutuo o el acceso de los centros directivos a la herramienta indexUNE (mecanismo de suministro de informaci\u00f3n actualizada sobre las normas UNE).<\/p>\n<p>En los procesos de unificaci\u00f3n e intercambio de informaci\u00f3n, BIM tiene mucho que aportar. La interoperabilidad es una de las principales ventajas del modelo Building Information Modeling, que cada vez est\u00e1 m\u00e1s presente en la Administraci\u00f3n P\u00fablica y en general en todo el sector AECO, cuyos profesionales valoran cada vez m\u00e1s una adecuada formaci\u00f3n en esta metodolog\u00eda colaborativa, en especial a trav\u00e9s de alguno de los programas de <a href=\"https:\/\/www.master-bim.online\/\" title=\"m\u00e1ster BIM\" rel=\"nofollow\">m\u00e1ster BIM<\/a> que se ofertan. De hecho, MITMA colabora en la actualidad con la UNE para facilitar el uso de dicha metodolog\u00eda de trabajo colaborativo en la contrataci\u00f3n p\u00fablica.<\/p>\n<p>UNE forma parte del comit\u00e9 t\u00e9cnico de la Comisi\u00f3n Interministerial BIM, dirigida a facilitar el uso de esta tecnolog\u00eda y filosof\u00eda de trabajo en los contratos p\u00fablicos de los \u00e1mbitos de las infraestructuras de carreteras y ferroviarias, de vivienda y edificaci\u00f3n, de productos de construcci\u00f3n, as\u00ed como de equipos y sistemas que sirven de apoyo a los diferentes tipos de transporte.<\/p>\n<p>A trav\u00e9s de expertos en la materia, la Comisi\u00f3n Interministerial BIM se encarga en la actualidad de dar forma al denominado Plan BIM, y trabaja en la elaboraci\u00f3n de documentaci\u00f3n t\u00e9cnica relevante, en la que se emplean normas UNE, para garantizar una adecuada implantaci\u00f3n de esta metodolog\u00eda.<\/p>\n<p>Las normas o est\u00e1ndares de UNE son documentos t\u00e9cnicos de aplicaci\u00f3n voluntaria que elabora la Asociaci\u00f3n sin \u00e1nimo de lucro por consenso entre los fabricantes de productos\/proveedores de servicios, los consumidores de esos productos\/servicios y la Administraci\u00f3n, lo que sirve para tipificar las caracter\u00edsticas que tienen esos productos o servicios objetos de la norma, intentando hacerlos compatibles con otros igualmente normalizados. Esta tipificaci\u00f3n facilita la posterior utilizaci\u00f3n de esos productos o servicios en todo el sector de la construcci\u00f3n, incluso en el \u00e1mbito internacional.<\/p>\n<p class=\"mediakit\"> Fuente <a href=\"https:\/\/www.comunicae.es\/notas-de-prensa\/bim-y-el-mitma-favorecen-un-mejor-uso-de-las\/\">Comunicae<\/a><\/p>\n<p><img decoding=\"async\" loading=\"lazy\" class=\"mediakit\" src=\"https:\/\/www.comunicae.es\/notificaLectura.php?tipoCanalId=75&amp;notaId=1245041\" width=\"1px\" height=\"1px\"><\/p>\n<p>The post <a rel=\"nofollow\" href=\"https:\/\/tecnobitt.com\/bim-y-el-mitma-favorecen-un-mejor-uso-de-las-normas-en-la-administracion-publica\/\">BIM y el MITMA favorecen un mejor uso de las normas en la Administraci\u00f3n P\u00fablica<\/a> appeared first on <a rel=\"nofollow\" href=\"https:\/\/tecnobitt.com\/\">TecnoBitt :- Un bit de tecnolog\u00eda diaria<\/a>.<\/p>\n<\/div>\n<p><img decoding=\"async\" class=\"wpe_imgrss\" src=\"https:\/\/tecnobitt.com\/wp-content\/uploads\/2023\/04\/bim-y-el-mitma-favorecen-un-mejor-uso-de-las-normas-en-la-administracion-publica-1024x326.jpg\"><\/p>\n<p><img decoding=\"async\" class=\"wpe_imgrss\" src=\"https:\/\/diarioemprendedor.com\/wp-content\/uploads\/2023\/04\/bim-y-el-mitma-favorecen-un-mejor-uso-de-las-normas-en-la-administracion-publica-1024x326-1-768x245.jpg\"><\/p>\n","protected":false},"excerpt":{"rendered":"BIM y el MITMA favorecen un mejor uso de las normas en la Administraci\u00f3n P\u00fablica BIM y el&hellip;","protected":false},"author":2,"featured_media":38782,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"csco_display_header_overlay":false,"csco_singular_sidebar":"","csco_page_header_type":"","csco_page_load_nextpost":"","csco_post_video_location":[],"csco_post_video_location_hash":"","csco_post_video_url":"","csco_post_video_bg_start_time":0,"csco_post_video_bg_end_time":0,"footnotes":""},"categories":[554,537,426,762,729,427,763,764,765,81,466,766],"tags":[114],"class_list":["post-38781","post","type-post","status-publish","format-standard","has-post-thumbnail","category-actualidad","category-arquitectura","category-destacado","category-ecocistema","category-entrevistas","category-featured","category-inversiones","category-noticia","category-noticias","category-software","category-startups","category-venture-capital","tag-destacado","cs-entry","cs-video-wrap"],"_links":{"self":[{"href":"https:\/\/iberopress.es\/index.php\/wp-json\/wp\/v2\/posts\/38781","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/iberopress.es\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/iberopress.es\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/iberopress.es\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/iberopress.es\/index.php\/wp-json\/wp\/v2\/comments?post=38781"}],"version-history":[{"count":0,"href":"https:\/\/iberopress.es\/index.php\/wp-json\/wp\/v2\/posts\/38781\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/iberopress.es\/index.php\/wp-json\/wp\/v2\/media\/38782"}],"wp:attachment":[{"href":"https:\/\/iberopress.es\/index.php\/wp-json\/wp\/v2\/media?parent=38781"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/iberopress.es\/index.php\/wp-json\/wp\/v2\/categories?post=38781"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/iberopress.es\/index.php\/wp-json\/wp\/v2\/tags?post=38781"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}